{"id":19650,"date":"2020-05-20T08:11:19","date_gmt":"2020-05-20T03:11:19","guid":{"rendered":"http:\/\/www.theajmals.com\/blog\/?p=19650"},"modified":"2020-05-20T08:11:19","modified_gmt":"2020-05-20T03:11:19","slug":"%d8%a7%d9%90%d9%86%d8%b3%d8%a7%d9%86%db%8c-%d8%ac%d8%b3%d9%85-%da%a9%db%8c-%d9%81%db%8c%da%a9%d9%b9%d8%b1%db%8c%d8%a7%da%ba","status":"publish","type":"post","link":"https:\/\/theajmals.com\/blog\/2020\/05\/%d8%a7%d9%90%d9%86%d8%b3%d8%a7%d9%86%db%8c-%d8%ac%d8%b3%d9%85-%da%a9%db%8c-%d9%81%db%8c%da%a9%d9%b9%d8%b1%db%8c%d8%a7%da%ba\/","title":{"rendered":"\u0627\u0650\u0646\u0633\u0627\u0646\u06cc \u062c\u0633\u0645 \u06a9\u06cc \u0641\u06cc\u06a9\u0679\u0631\u06cc\u0627\u06ba"},"content":{"rendered":"<p style=\"font-family:Nafees Web Naskh,Arial,Urdu Naskh Asiatype,Tahoma,Unicode MS;font-size:18px;direction:rtl;text-align:right;\">\n\ufba8\ufee4\ufe8e\ufead\ufbae Pancreas \u200f\ufedf\ufe92\ufee0\ufe92\ufbaf \u200f\ufea7\ufeee\ufee5 \ufee3\ufbff\ufb9f \ufeb7\ufeee\ufb94\ufeae \ufb90\ufbfd \ufe8d\ufbfe\ufb8f \ufea7\ufe8e\ufeb9 \ufee3\ufed8\ufeaa\ufe8d\ufead \ufb90\ufeee \ufe91\ufb8d\ufbac\ufee8\ufbaf \ufee7\ufba9\ufbff\ufb9f \ufea9\ufbfe\ufe98\ufbaf \u060c \ufea9\ufedd \ufb90\ufe8e \ufb58\ufee4\ufb57 \ufba8\ufeae \ufee3\ufee8\ufb67 \ufeb3\ufe98\ufeae \ufe8d\ufeb3\ufbfd \ufea9\ufed3\ufecc\ufba7 \u0645\u0646\u0638\u0645 \u0628\u0627\u0642\u0627\u0639\u062f\u06c1 \u062d\u0631\u06a9\u062a \u0633\u06d2 \ufea7\ufeee\ufee5 \ufb58\ufee4\ufb57 \ufb90\ufeae\ufe97\ufe8e \ufead\ufba8\ufe98\ufe8e \ufba8\ufbaf \ufe8d\ufbfe\ufb8f 75\ufeb3\ufe8e\ufedf\ufba7 \ufeaf\ufee7\ufeaa\ufb94\ufbfd \ufee3\ufbff\ufb9f \ufe91\ufefc \ufee3\ufeae\ufee3\ufe96 \ufe97\ufed8\ufeae\ufbfe\ufe92\u064b\ufe8e \ufe97\ufbff\ufee6 \ufe8d\ufead\ufe8f \ufe91\ufe8e\ufead \ufea9\ufbac\ufb8d\ufb90\ufe98\ufe8e \ufba8\ufbaf\u06d4\n<\/p>\n<p style=\"font-family:Nafees Web Naskh,Arial,Urdu Naskh Asiatype,Tahoma,Unicode MS;font-size:18px;direction:rtl;text-align:right;\">\n\ufba8\ufee4\ufe8e\ufead\ufbae \ufb94\ufeae\ufea9\ufbae \u200f( Kidneys \u200f) \ufebb\ufed4\ufe8e\ufe8b\ufbfd \ufb90\ufbfd \ufe91\ufbaf\ufee3\ufe9c\ufede \ufe8d\ufeed\ufead \ufecb\ufea0\ufbff\ufe90 \ufed3\ufbff\ufb91\ufb69\ufeae\ufbfc \u06c1\u06cc\u06ba \ufe9f\ufeee \ufe9f\ufe8e\ufee7\ufe98\ufbfd \ufba8\ufbaf \ufb90\ufba7 \ufea7\ufeee\ufee5 \ufee3\ufbff\ufb9f \ufe9f\ufeb4\ufee2 \u06a9\u06d2 \u0644\u0626\u06d2 \ufe9f\ufeee \ufee3\ufed4\ufbff\ufeaa \ufba8\ufbaf\ufeed\u06d5 \ufead\ufb90\ufbab \ufedf\ufbff\ufee8\ufe8e \ufba8\ufbaf \u0627\u0648\u0631 \ufed3\ufec0\ufefc\ufe95 \ufb90\ufeee \ufe91\ufe8e\ufba8\ufeae \ufb58\ufbad\ufbff\ufee8\ufb8f \ufea9\ufbfe\ufee8\ufe8e \ufba8\ufbaf\u06d4\n<\/p>\n<p style=\"font-family:Nafees Web Naskh,Arial,Urdu Naskh Asiatype,Tahoma,Unicode MS;font-size:18px;direction:rtl;text-align:right;\">\n\ufee3\ufecc\ufeaa\u06d5 \ufea3\ufbff\ufeae\ufe8d\ufee5 \ufb90\ufee6 \ufb90\ufbff\ufee4\ufbff\ufb91\ufede \ufb90\ufee4\ufb59\ufee0\ufbff\ufb91\ufeb2 \u200f( Chemical Complex \u200f) \ufba8\ufbaf \ufe9f\ufeee \ufea7\ufeee\ufead\ufe8d\ufb8e \ufeb3\ufbaf \ufeaf\ufee7\ufeaa\ufb94\ufbfd \ufe91\ufea8\ufeb6 \ufe8d\ufe9f\ufeb0\ufe8d \ufee3\ufe9c\ufee0\u064b\ufe8e \ufb58\ufeae\ufeed\ufb68\ufbff\ufee6 \u060c\ufb90\ufe8e\ufead\ufe91\ufeee\ufba8\ufe8e\ufe8b\ufbff\ufb89\ufead\u06cc\u0679\u0633 \ufeed\ufecf\ufbff\ufeae\u06d5 \ufb90\ufeee \ufecb\ufee0\ufbff\ufea4\ufeaa\u06d5 \ufb90\ufeae\ufb90\ufbaf \ufea7\ufeee\ufee5 \ufb90\ufbaf \ufea3\ufeee\ufe8d\ufedf\ufba7 \ufb90\ufeae \ufea9\ufbfe\ufe98\ufe8e \ufba8\ufbaf \ufe8d\ufeed\ufead \ufed3\ufec0\ufefc\ufe95 \ufb90\ufeee \ufe91\ufe8e\ufba8\ufeae \ufee7\ufb91\ufe8e\ufedd \ufea9\ufbfe\ufe98\ufe8e \ufba8\ufbaf\u06d4\n<\/p>\n<p style=\"font-family:Nafees Web Naskh,Arial,Urdu Naskh Asiatype,Tahoma,Unicode MS;font-size:18px;direction:rtl;text-align:right;\">\n\ufe8d\ufee7\ufeb4\ufe8e\ufee7\ufbfd \ufe9f\ufeb4\ufee2 \ufee3\ufbff\ufb9f \ufe8d\ufee7\ufea0\ufbff\ufee8\ufe8c\ufeae\ufee7\ufb93 \ufb90\ufbaf \ufbfe\ufba7 \ufeb7\ufe8e\ufba8\ufb91\ufe8e\ufead\u060c \ufeb3\ufe8e\ufe8b\ufee8\ufeb2 \ufb90\ufbaf \ufbfe\ufba7 \ufe91\ufbaf \ufee3\ufe9c\ufede \ufee7\ufee4\ufeee\ufee7\ufbaf\u060c \ufb7c\ufbad\ufeee\ufb68\ufbaf \ufeb3\ufbaf \ufb58\ufbff\ufb67 \ufee3\ufbff\ufb9f \ufbfe\ufba7 \ufefb\ufe9f\ufeee\ufe8d\ufe8f \ufed3\ufbff\ufb91\ufb69\ufeae\ufbfe\ufe8e\ufb9e \u060c \ufb90\ufbff\ufe8e \ufbfe\ufba7 \ufeb3\ufe90 \ufb90\ufb7d\ufbab \ufbfe\ufeee\ufb9e \ufba8\ufbfd \ufe91\ufee6 \ufb94\ufbb1 \ufe97\ufbad\ufbaf\u061f\n<\/p>\n<p style=\"font-size: 28px; direction: rtl; font-family: Nafees Web Naskh,Arial,Urdu Naskh Asiatype,Tahoma,Unicode MS; text-align:right\">\n\u0644\u0627 \u0627\u0644\u0670\u0647 \u0627\u0644\u0627 \u0627\u0644\u0644\u0647<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\ufba8\ufee4\ufe8e\ufead\ufbae Pancreas \u200f\ufedf\ufe92\ufee0\ufe92\ufbaf \u200f\ufea7\ufeee\ufee5 \ufee3\ufbff\ufb9f \ufeb7\ufeee\ufb94\ufeae \ufb90\ufbfd \ufe8d\ufbfe\ufb8f \ufea7\ufe8e\ufeb9 \ufee3\ufed8\ufeaa\ufe8d\ufead \ufb90\ufeee \ufe91\ufb8d\ufbac\ufee8\ufbaf \ufee7\ufba9\ufbff\ufb9f \ufea9\ufbfe\ufe98\ufbaf \u060c \ufea9\ufedd \ufb90\ufe8e \ufb58\ufee4\ufb57 \ufba8\ufeae \ufee3\ufee8\ufb67 \ufeb3\ufe98\ufeae \ufe8d\ufeb3\ufbfd \ufea9\ufed3\ufecc\ufba7 \u0645\u0646\u0638\u0645 \u0628\u0627\u0642\u0627\u0639\u062f\u06c1 \u062d\u0631\u06a9\u062a \u0633\u06d2 \ufea7\ufeee\ufee5 \ufb58\ufee4\ufb57 \ufb90\ufeae\ufe97\ufe8e \ufead\ufba8\ufe98\ufe8e \ufba8\ufbaf \ufe8d\ufbfe\ufb8f 75\ufeb3\ufe8e\ufedf\ufba7 \ufeaf\ufee7\ufeaa\ufb94\ufbfd \ufee3\ufbff\ufb9f \ufe91\ufefc \ufee3\ufeae\ufee3\ufe96 \ufe97\ufed8\ufeae\ufbfe\ufe92\u064b\ufe8e \ufe97\ufbff\ufee6 \ufe8d\ufead\ufe8f \ufe91\ufe8e\ufead \ufea9\ufbac\ufb8d\ufb90\ufe98\ufe8e \ufba8\ufbaf\u06d4 \ufba8\ufee4\ufe8e\ufead\ufbae \ufb94\ufeae\ufea9\ufbae \u200f( Kidneys \u200f) \ufebb\ufed4\ufe8e\ufe8b\ufbfd \ufb90\ufbfd \ufe91\ufbaf\ufee3\ufe9c\ufede \ufe8d\ufeed\ufead \ufecb\ufea0\ufbff\ufe90 \ufed3\ufbff\ufb91\ufb69\ufeae\ufbfc [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[24,15,35,5],"tags":[],"class_list":["post-19650","post","type-post","status-publish","format-standard","hentry","category-24","category-15","category-35","category-5"],"views":1736,"_links":{"self":[{"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/posts\/19650","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/comments?post=19650"}],"version-history":[{"count":1,"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/posts\/19650\/revisions"}],"predecessor-version":[{"id":19651,"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/posts\/19650\/revisions\/19651"}],"wp:attachment":[{"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/media?parent=19650"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/categories?post=19650"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/theajmals.com\/blog\/wp-json\/wp\/v2\/tags?post=19650"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}